{"id":101272,"date":"2026-02-22T00:24:57","date_gmt":"2026-02-21T23:24:57","guid":{"rendered":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/automatisch-gespeicherter-entwurf"},"modified":"2026-02-22T00:24:58","modified_gmt":"2026-02-21T23:24:58","slug":"gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","status":"publish","type":"post","link":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","title":{"rendered":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten. Besonders macht die Berliner Erfinder, dass sie ein echtes H\u00e4ndchen f\u00fcr die Vorlieben der Spieler haben und das nicht nur hierzulande. Es ist ihnen n\u00e4mlich gelungen, bereits mehrere zeitlose Klassiker in das Spielsortiment der Online Casinos zu integrieren. Ramses Book ist einer von ihnen und mit Legacy of Ramses Book ist es nun in einer Neuauflage erschienen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gamomat stellt Legacy of Ramses Book vor<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Am Donnerstag, den 19. Februar 2026 war es endlich so weit. Gamomat stellte <a href=\"https:\/\/gamomat.berlin\/news\/gamomat-builds-on-its-iconic-ramses-book-with-the-launch-of-legacy-of-ramses-book\/\" target=\"_blank\" rel=\"noreferrer noopener\">Legacy of Ramses Book der \u00d6ffentlichkeit <\/a>(Link in Englisch) vor. Gamomat blieb sich bei dieser neuesten Ausgabe seines h\u00f6chst erfolgreichen Spieletitels treu. Legacy of Ramses Book ist daher mit nahezu s\u00e4mtlichen beliebten Bonus-Funktionen des bereits vor Jahren erschienenen Spiels ausgestattet. Auch die Story ist identisch, denn die Spieler werden abermals nach \u00c4gypten reisen, wo K\u00f6nig Ramses einige echte \u00dcberraschungen f\u00fcr sie vorbereitet hat.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Legacy of Ramses Book wurden einige \u201cModernisierungen\u201d des Spiels vorgenommen. Insbesondere der Soundtrack f\u00e4llt direkt auf. Aber auch bei den Bonus-Funktionen gibt es Neues zu entdecken. Die Freispielrunde ist jetzt etwa mit einer Multi-Symbol-Mechanik ausgestattet. Das als kombiniertes Wild- und Scatter Symbol fungierende Buch ist jedoch nicht das einzige Bonus-Symbol. W\u00e4hrend der Freispiele werden sich mit den gestempelten Bonus Symbolen weitere Symbole auf den Walzen befinden, nach denen man Ausschau halten sollte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Freispielrunde geht es zudem besonders hei\u00df her, denn Gamomat hat sich mit dem Symbol Upgrade eine echte \u00dcberraschung einfallen lassen. Jedes Mal, wenn mindestens drei B\u00fcchersymbole landen, wird ein beliebiges Symbol in eines der vorher nach dem Zufallsprinzip ausgew\u00e4hlten Bonus-Symbole verwandelt. Diese Bonusrunde kann zudem nochmals ausgew\u00e4hlt werden, in diesem Fall erhalten die Spieler zehn weitere Freispiele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten. Besonders macht die Berliner Erfinder, dass sie ein echtes H\u00e4ndchen f\u00fcr die Vorlieben der Spieler haben und das nicht nur hierzulande. Es ist ihnen n\u00e4mlich gelungen, bereits mehrere zeitlose Klassiker in das Spielsortiment der Online Casinos zu integrieren. Ramses Book ist einer von [&hellip;]<\/p>\n","protected":false},"author":227,"featured_media":101273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"gi_category":[20],"gi_region":[],"class_list":["post-101272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","gi_category-spielautomaten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe<\/title>\n<meta name=\"description\" content=\"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe\" \/>\n<meta property=\"og:description\" content=\"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\" \/>\n<meta property=\"og:site_name\" content=\"Gambling Insider Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-21T23:24:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-21T23:24:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"802\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anja Sellman-Reiner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anja Sellman-Reiner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\"},\"author\":{\"name\":\"Anja Sellman-Reiner\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#\\\/schema\\\/person\\\/97b8dbc029f3f0b77bd352af9870a0d4\"},\"headline\":\"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe\",\"datePublished\":\"2026-02-21T23:24:57+00:00\",\"dateModified\":\"2026-02-21T23:24:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\"},\"wordCount\":304,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/stokpic-gambling-602976_optimized.jpg\",\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\",\"name\":\"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/stokpic-gambling-602976_optimized.jpg\",\"datePublished\":\"2026-02-21T23:24:57+00:00\",\"dateModified\":\"2026-02-21T23:24:58+00:00\",\"description\":\"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/stokpic-gambling-602976_optimized.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/stokpic-gambling-602976_optimized.jpg\",\"width\":1200,\"height\":802,\"caption\":\"Bild von stokpic auf Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/news\\\/101272\\\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/\",\"name\":\"Gambling Insider Deutsch\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#organization\",\"name\":\"Gambling Insider Deutsch\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/featured_image-180.png\",\"contentUrl\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/featured_image-180.png\",\"width\":180,\"height\":180,\"caption\":\"Gambling Insider Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/#\\\/schema\\\/person\\\/97b8dbc029f3f0b77bd352af9870a0d4\",\"name\":\"Anja Sellman-Reiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/avatar_user_227_1770720369-96x96.png\",\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/avatar_user_227_1770720369-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/avatar_user_227_1770720369-96x96.png\",\"caption\":\"Anja Sellman-Reiner\"},\"url\":\"https:\\\/\\\/www.gamblinginsider.com\\\/de\\\/author\\\/anja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe","description":"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","og_locale":"de_DE","og_type":"article","og_title":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe","og_description":"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe","og_url":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","og_site_name":"Gambling Insider Deutsch","article_published_time":"2026-02-21T23:24:57+00:00","article_modified_time":"2026-02-21T23:24:58+00:00","og_image":[{"width":1200,"height":802,"url":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg","type":"image\/jpeg"}],"author":"Anja Sellman-Reiner","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anja Sellman-Reiner","Est. reading time":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#article","isPartOf":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe"},"author":{"name":"Anja Sellman-Reiner","@id":"https:\/\/www.gamblinginsider.com\/de\/#\/schema\/person\/97b8dbc029f3f0b77bd352af9870a0d4"},"headline":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe","datePublished":"2026-02-21T23:24:57+00:00","dateModified":"2026-02-21T23:24:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe"},"wordCount":304,"publisher":{"@id":"https:\/\/www.gamblinginsider.com\/de\/#organization"},"image":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage"},"thumbnailUrl":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg","inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.gamblinginsider.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","url":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe","name":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe","isPartOf":{"@id":"https:\/\/www.gamblinginsider.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage"},"image":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage"},"thumbnailUrl":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg","datePublished":"2026-02-21T23:24:57+00:00","dateModified":"2026-02-21T23:24:58+00:00","description":"Der deutsche Spiele-Hersteller Gamomat ist ein echter Spezialist in Sachen Online Spielautomaten: Neuer Titel der Ramses Book Reihe","breadcrumb":{"@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#primaryimage","url":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg","contentUrl":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/stokpic-gambling-602976_optimized.jpg","width":1200,"height":802,"caption":"Bild von stokpic auf Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gamblinginsider.com\/de\/news\/101272\/gamomat-veroeffentlicht-neuesten-titel-der-ramses-book-reihe#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gamblinginsider.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gamomat ver\u00f6ffentlicht neuesten Titel der Ramses Book Reihe"}]},{"@type":"WebSite","@id":"https:\/\/www.gamblinginsider.com\/de\/#website","url":"https:\/\/www.gamblinginsider.com\/de\/","name":"Gambling Insider Deutsch","description":"","publisher":{"@id":"https:\/\/www.gamblinginsider.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gamblinginsider.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gamblinginsider.com\/de\/#organization","name":"Gambling Insider Deutsch","url":"https:\/\/www.gamblinginsider.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gamblinginsider.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/featured_image-180.png","contentUrl":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/featured_image-180.png","width":180,"height":180,"caption":"Gambling Insider Deutsch"},"image":{"@id":"https:\/\/www.gamblinginsider.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gamblinginsider.com\/de\/#\/schema\/person\/97b8dbc029f3f0b77bd352af9870a0d4","name":"Anja Sellman-Reiner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/avatar_user_227_1770720369-96x96.png","url":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/avatar_user_227_1770720369-96x96.png","contentUrl":"https:\/\/www.gamblinginsider.com\/de\/wp-content\/uploads\/sites\/2\/2026\/02\/avatar_user_227_1770720369-96x96.png","caption":"Anja Sellman-Reiner"},"url":"https:\/\/www.gamblinginsider.com\/de\/author\/anja"}]}},"modified_by":"jasmin","_links":{"self":[{"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/posts\/101272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/comments?post=101272"}],"version-history":[{"count":1,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/posts\/101272\/revisions"}],"predecessor-version":[{"id":101274,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/posts\/101272\/revisions\/101274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/media\/101273"}],"wp:attachment":[{"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/media?parent=101272"}],"wp:term":[{"taxonomy":"gi_category","embeddable":true,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/gi_category?post=101272"},{"taxonomy":"gi_region","embeddable":true,"href":"https:\/\/www.gamblinginsider.com\/de\/wp-json\/wp\/v2\/gi_region?post=101272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}